{"id":17137,"date":"2022-12-19T15:58:17","date_gmt":"2022-12-19T23:58:17","guid":{"rendered":"https:\/\/vccf.org\/?p=17137"},"modified":"2025-03-03T06:20:41","modified_gmt":"2025-03-03T14:20:41","slug":"vccf-end-of-year-letter-2022","status":"publish","type":"post","link":"https:\/\/vccf.org\/es\/vccf-end-of-year-letter-2022\/","title":{"rendered":"Carta de fin de a\u00f1o de la VCCF 2022"},"content":{"rendered":"<div id=\"attachment_17139\" style=\"width: 810px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-17139\" class=\"wp-image-17139\" src=\"https:\/\/vccf.org\/wp-content\/uploads\/2022\/12\/vccf12-5-22-lr-052-scaled-2.jpg\" alt=\"\" width=\"800\" height=\"533\" \/><p id=\"caption-attachment-17139\" class=\"wp-caption-text\">\u00a1Felices fiestas y pr\u00f3spero a\u00f1o nuevo de parte del equipo de la VCCF!<\/p><\/div>\n\n\n<p class=\"already_translated\">Estimada familia de la Fundaci\u00f3n Comunitaria del Condado de Ventura,<\/p>\n<p class=\"already_translated\"><strong>Este a\u00f1o hemos sido testigos de tanta generosidad en toda nuestra regi\u00f3n<\/strong>\u00a0y nos llena el coraz\u00f3n de gratitud. Estamos asombrados de su compasi\u00f3n y compromiso con nuestra comunidad y no podemos agradecerles lo suficiente todo lo que est\u00e1n haciendo para crear un impacto duradero en nuestro mundo compartido.<\/p>\n<p class=\"already_translated\">Recordamos la\u00a0<strong>primera subvenci\u00f3n en 2022<\/strong>que ayud\u00f3 a una organizaci\u00f3n local sin \u00e1nimo de lucro a comprar art\u00edculos dom\u00e9sticos esenciales para\u00a0<strong>mujeres, ni\u00f1os y animales dom\u00e9sticos que huyen de situaciones de violencia dom\u00e9stica<\/strong>\u00a0y que necesitan un lugar seguro donde quedarse mientras se les consigue una vivienda permanente.<\/p>\n<p class=\"already_translated\">Este a\u00f1o, usted ha ayudado a las personas que reciben atenci\u00f3n en\u00a0<strong>Hospital de convalecencia y enfermer\u00eda Mary Health of the Sick<\/strong>y has concedido\u00a0<strong>becas a cientos de estudiantes locales<\/strong>\u00a0perseguir sus sue\u00f1os de educaci\u00f3n superior y formaci\u00f3n profesional.<\/p>\n<p class=\"already_translated\">Juntos, hab\u00e9is patrocinado los deseos de ni\u00f1os que reciben tratamiento contra el c\u00e1ncer a trav\u00e9s de subvenciones concedidas a\u00a0<strong>Make-A-Wish Tri-Counties<\/strong>y has ayudado a cubrir los costes de formaci\u00f3n en el\u00a0<strong>Fundaci\u00f3n Nacional de Perros de B\u00fasqueda para Cat\u00e1strofes<\/strong>. Han aportado fondos esenciales para\u00a0<strong>investigaci\u00f3n sobre el c\u00e1ncer de p\u00e1ncreas<\/strong>\u00a0y tienen\u00a0<strong>ayud\u00f3 a las v\u00edctimas de los incendios locales a conseguir finalmente una vivienda permanente<\/strong>\u00a0tras sufrir la devastaci\u00f3n de los incendios Thomas, Hill y Woolsey.<\/p>\n<p class=\"already_translated\">Gracias a ti, <strong>alumnos de secundaria de Oxnard asisten a un campamento cient\u00edfico<\/strong>\u00a0por primera vez y un\u00a0<strong>el instituto local tendr\u00e1 una nueva biblioteca<\/strong>. Usted ha permitido\u00a0<strong>clases de nataci\u00f3n a ni\u00f1os con bajos ingresos<\/strong>\u00a0y han patrocinado docenas de\u00a0<strong>experiencias art\u00edsticas y culturales<\/strong>\u00a0en toda nuestra regi\u00f3n de diez ciudades. Juntos, han sufragado los costes asociados a\u00a0<strong>esfuerzos locales para reducir el riesgo de incendios forestales<\/strong>\u00a0y han ayudado a proteger\u00a0<strong>mariposas monarca<\/strong>\u00a0de extinguirse gracias a una importante subvenci\u00f3n concedida a\u00a0<strong>Girl Scouts de la Costa Central de California<\/strong>...\u00a1la lista es interminable!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-22698 size-medium alignleft\" src=\"https:\/\/vccf.org\/wp-content\/uploads\/2022\/12\/vccf12-5-22-lr-057-scaled-e1671487578720-300x294.jpg\" sizes=\"auto, (max-width: 485px) 100vw, 485px\" srcset=\"https:\/\/vccf.org\/wp-content\/uploads\/2022\/12\/vccf12-5-22-lr-057-scaled-e1671487578720.jpg 1296w, https:\/\/vccf.org\/wp-content\/uploads\/2022\/12\/vccf12-5-22-lr-057-scaled-e1671487578720-300x294.jpg 300w, https:\/\/vccf.org\/wp-content\/uploads\/2022\/12\/vccf12-5-22-lr-057-scaled-e1671487578720-1024x1005.jpg 1024w, https:\/\/vccf.org\/wp-content\/uploads\/2022\/12\/vccf12-5-22-lr-057-scaled-e1671487578720-768x754.jpg 768w, https:\/\/vccf.org\/wp-content\/uploads\/2022\/12\/vccf12-5-22-lr-057-scaled-e1671487578720-265x260.jpg 265w, https:\/\/vccf.org\/wp-content\/uploads\/2022\/12\/vccf12-5-22-lr-057-scaled-e1671487578720-782x768.jpg 782w, https:\/\/vccf.org\/wp-content\/uploads\/2022\/12\/vccf12-5-22-lr-057-scaled-e1671487578720-422x414.jpg 422w, https:\/\/vccf.org\/wp-content\/uploads\/2022\/12\/vccf12-5-22-lr-057-scaled-e1671487578720-1280x1256.jpg 1280w, https:\/\/vccf.org\/wp-content\/uploads\/2022\/12\/vccf12-5-22-lr-057-scaled-e1671487578720-414x406.jpg 414w\" alt=\"\" width=\"300\" height=\"294\" \/><\/p>\n<p>Colectivamente,\u00a0<strong>ha concedido m\u00e1s de $20 millones este a\u00f1o\u00a0<\/strong>y su generosidad contin\u00faa, con su subvenci\u00f3n m\u00e1s reciente firmada esta ma\u00f1ana destinada a ayudar a la\u00a0<strong>Club de Ni\u00f1os y Ni\u00f1as de Camarillo<\/strong>\u00a0ampliaci\u00f3n de capital, un programa comunitario vital que atiende hasta 500 ni\u00f1os al d\u00eda.<\/p>\n<p class=\"already_translated\">A pesar de todo, segu\u00eds preguntando qu\u00e9 m\u00e1s se necesita y qu\u00e9 m\u00e1s se puede hacer. Nos llenas de esperanza y haces que nuestro mundo sea m\u00e1s brillante.<\/p>\n<p>De todo coraz\u00f3n,<br \/>Sean Leonard, Presidente del Consejo de Administraci\u00f3n de la VCCF y Vanessa Bechtel, Presidenta y Directora General de la VCCF<\/p>","protected":false},"excerpt":{"rendered":"<p>Dear Ventura County Community Foundation Family, We have witnessed such generosity throughout our region this past year\u00a0and it fills our hearts with gratitude. We are in awe of your compassion&hellip;<\/p>","protected":false},"author":3,"featured_media":17139,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"footnotes":""},"categories":[27],"tags":[],"class_list":["post-17137","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-posts"],"_links":{"self":[{"href":"https:\/\/vccf.org\/es\/wp-json\/wp\/v2\/posts\/17137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vccf.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vccf.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vccf.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/vccf.org\/es\/wp-json\/wp\/v2\/comments?post=17137"}],"version-history":[{"count":0,"href":"https:\/\/vccf.org\/es\/wp-json\/wp\/v2\/posts\/17137\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vccf.org\/es\/wp-json\/wp\/v2\/media\/17139"}],"wp:attachment":[{"href":"https:\/\/vccf.org\/es\/wp-json\/wp\/v2\/media?parent=17137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vccf.org\/es\/wp-json\/wp\/v2\/categories?post=17137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vccf.org\/es\/wp-json\/wp\/v2\/tags?post=17137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}