{"id":13253,"date":"2021-07-30T14:57:46","date_gmt":"2021-07-30T21:57:46","guid":{"rendered":"https:\/\/vccf.org\/?p=13253"},"modified":"2026-02-26T11:00:32","modified_gmt":"2026-02-26T19:00:32","slug":"regions-foundations-enter-next-phase-of-pandemic-relief","status":"publish","type":"post","link":"https:\/\/vccf.org\/fr\/regions-foundations-enter-next-phase-of-pandemic-relief\/","title":{"rendered":"Les fondations de la r\u00e9gion entrent dans la phase suivante de l'aide \u00e0 la lutte contre la pand\u00e9mie"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><em>Cet article a \u00e9t\u00e9 publi\u00e9 \u00e0 l'origine dans <a href=\"https:\/\/www.pacbiztimes.com\/2021\/07\/30\/regions-foundations-enter-next-phase-of-pandemic-relief\/\" target=\"_blank\" rel=\"noopener\">Pacific Coast Business Times<\/a>.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le COVID-19 Joint Response Effort du comt\u00e9 de Santa Barbara a ferm\u00e9 son fonds de secours \u00e0 la mi-juillet apr\u00e8s avoir distribu\u00e9 $5,8 millions, bien que d'autres fonds de secours dans toute la r\u00e9gion restent actifs et continuent d'aider les personnes, les entreprises et les organisations \u00e0 but non lucratif \u00e0 faire face \u00e0 la pand\u00e9mie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Fondation de Santa Barbara, la Fondation communautaire du comt\u00e9 de Ventura et la Fondation communautaire du comt\u00e9 de San Luis Obispo ont toutes trois collect\u00e9 et distribu\u00e9 des fonds et aid\u00e9 \u00e0 coordonner les efforts de secours d'autres organisations \u00e0 but non lucratif. Dans le comt\u00e9 de Santa Barbara, la fondation s'est associ\u00e9e \u00e0 United Way of Santa Barbara County et \u00e0 la Hutton Parker Foundation pour former ce que Jackie Carrera, PDG de la Santa Barbara Foundation, a appel\u00e9 \"un tabouret \u00e0 trois pieds\".<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les trois groupes se sont r\u00e9unis chaque semaine pendant 65 semaines pour organiser et distribuer les fonds. Sur les $5,8 millions, $3,2 millions ont \u00e9t\u00e9 donn\u00e9s \u00e0 d'autres organisations \u00e0 but non lucratif pour leurs efforts de secours, et $2,6 millions sont all\u00e9s directement aux personnes dans le besoin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans les deux cas, l'argent \u00e9tait destin\u00e9 aux personnes les plus vuln\u00e9rables \u00e0 la pand\u00e9mie. Les types d'organisations \u00e0 but non lucratif qui ont re\u00e7u des subventions comprenaient celles qui travaillaient avec les personnes \u00e2g\u00e9es, les travailleurs essentiels, les \u00e9tudiants et les personnes ayant des probl\u00e8mes de sant\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\"Faire partie d'un partenariat \u00e0 un moment comme celui-ci n'est pas seulement important, c'est aussi un soulagement, et ce fut un plaisir de travailler avec eux tout au long de ce processus\", a d\u00e9clar\u00e9 M. Carrera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L'effort de r\u00e9ponse conjoint COVID-19 a pris fin le 14 juillet. Les cas de COVID-19 ont augment\u00e9 depuis lors, tandis que les taux de vaccination ont stagn\u00e9, et M. Carrera a d\u00e9clar\u00e9 que les organisations \u00e0 but non lucratif sont en train d'\u00e9valuer vers quoi leur attention devrait se tourner \u00e0 pr\u00e9sent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Ventura County Community Foundation a \u00e9galement mis en place divers programmes pour r\u00e9pondre \u00e0 la pand\u00e9mie. Le Ventura County Rapid Response Fund a accord\u00e9 plus de $1,5 million d'euros \u00e0 des organisations \u00e0 but non lucratif qui r\u00e9pondent \u00e0 des besoins fondamentaux tels que l'alimentation et le logement, la garde d'enfants, le remplacement des salaires et les soins de sant\u00e9 mentale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comme la Santa Barbara Foundation, la Ventura County Community Foundation s'est associ\u00e9e \u00e0 d'autres organisations \u00e0 but non lucratif et agences gouvernementales pour le Ventura County Rapid Response Fund. Le comt\u00e9 de Ventura, la fondation Amgen, le Southeast Ventura County YMCA, Give An Hour et l'Economic Development Collaborative en font partie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les refuges pour sans-abri, les anciens combattants, les travailleurs agricoles, les soins aux personnes \u00e2g\u00e9es et l'aide \u00e0 la location ne sont que quelques-unes des organisations qui ont re\u00e7u des fonds, a d\u00e9clar\u00e9 Vanessa Bechtel, directrice g\u00e9n\u00e9rale de la Ventura County Community Foundation. Safe Passage, une organisation \u00e0 but non lucratif qui soutient les jeunes, a livr\u00e9 plus de 140 000 repas \u00e0 des enfants et distribu\u00e9 60 000 couches \u00e0 des familles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\"J'ai \u00e9galement constat\u00e9 cette fois-ci, plus que jamais dans ma vie, l'effet cumulatif que nous pouvons avoir lorsque nous nous serrons les coudes\", a d\u00e9clar\u00e9 Mme Bechtel. Le soutien de milliers de primo-donateurs du comt\u00e9 de Ventura a eu un impact consid\u00e9rable, a-t-elle d\u00e9clar\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les fonds de secours de la fondation sont toujours actifs. \"Nous sommes simplement en train de r\u00e9orienter notre aide pour nous assurer qu'elle est pertinente et actuelle\", a d\u00e9clar\u00e9 M. Bechtel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le comt\u00e9 de San Luis Obispo, la Community Foundation San Luis Obispo a lanc\u00e9 le Disaster Support Fund en mars 2020. \"C'est de l'argent qui rentre et de l'argent qui sort\", a d\u00e9clar\u00e9 Heidi McPherson, directrice g\u00e9n\u00e9rale de la fondation, \u00e0 propos du programme de r\u00e9ponse rapide.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\"Nous avons re\u00e7u des centaines et des centaines de contributions pour un comt\u00e9 qui compte moins de 300 000 habitants\", a-t-elle d\u00e9clar\u00e9. \"C'est assez extraordinaire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces contributions ont aid\u00e9 la communaut\u00e9 de bien des fa\u00e7ons, notamment en finan\u00e7ant des programmes tels que des garderies pour les premiers intervenants au d\u00e9but de la pand\u00e9mie. La banque alimentaire de SLO a \u00e9galement re\u00e7u des fonds et s'est associ\u00e9e \u00e0 d'autres organisations pour \u00e9largir son champ d'action, par exemple en collaborant avec des associations de personnes \u00e2g\u00e9es pour distribuer des repas aux personnes \u00e2g\u00e9es bloqu\u00e9es chez elles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le fonds de soutien en cas de catastrophe est d\u00e9sormais ferm\u00e9, mais la Community Foundation San Luis Obispo accepte toujours les contributions et est pr\u00eate \u00e0 le rouvrir si n\u00e9cessaire, a d\u00e9clar\u00e9 Mme McPherson.<\/p>","protected":false},"excerpt":{"rendered":"<p>This story was originally published in Pacific Coast Business Times. Santa Barbara County\u2019s COVID-19 Joint Response Effort closed its relief fund in mid-July after distributing $5.8 million, though other relief&hellip;<\/p>","protected":false},"author":3,"featured_media":13255,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"give_campaign_id":0,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-13253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-latest-coverage"],"acf":[],"_links":{"self":[{"href":"https:\/\/vccf.org\/fr\/wp-json\/wp\/v2\/posts\/13253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vccf.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vccf.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vccf.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/vccf.org\/fr\/wp-json\/wp\/v2\/comments?post=13253"}],"version-history":[{"count":0,"href":"https:\/\/vccf.org\/fr\/wp-json\/wp\/v2\/posts\/13253\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vccf.org\/fr\/wp-json\/wp\/v2\/media\/13255"}],"wp:attachment":[{"href":"https:\/\/vccf.org\/fr\/wp-json\/wp\/v2\/media?parent=13253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vccf.org\/fr\/wp-json\/wp\/v2\/categories?post=13253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vccf.org\/fr\/wp-json\/wp\/v2\/tags?post=13253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}