{"id":3087,"date":"2018-06-21T12:18:08","date_gmt":"2018-06-21T19:18:08","guid":{"rendered":"https:\/\/vccf.org\/?p=3087"},"modified":"2025-01-29T07:48:38","modified_gmt":"2025-01-29T07:48:38","slug":"foundation-gets-new-vice-president","status":"publish","type":"post","link":"https:\/\/vccf.org\/fr\/foundation-gets-new-vice-president\/","title":{"rendered":"La Fondation se dote d'un nouveau vice-pr\u00e9sident"},"content":{"rendered":"<p><!--more--><\/p>\n<p><em>Lire l'article complet ci-dessous ou sur le site Acorn <a href=\"https:\/\/www.theacorn.com\/articles\/foundation-gets-new-vice-president\/\" target=\"_blank\" rel=\"noopener\">site web<\/a>.\u00a0<\/em><\/p>\n<p>La Ventura County Community Foundation a r\u00e9cemment annonc\u00e9 que Phylene Wiggins occupera le poste de vice-pr\u00e9sidente des programmes et des subventions.<\/p>\n<p>Dans ses nouvelles fonctions \u00e0 la VCCF, Mme Wiggins, originaire du comt\u00e9 de Ventura, travaillera directement avec des organisations \u00e0 but non lucratif, des entreprises et des organismes publics, ainsi qu'avec des particuliers, des familles et d'autres types d'organisations.<\/p>\n<p>Avant de rejoindre la VCCF, elle a fait partie du personnel de la Santa Barbara Foundation pendant pr\u00e8s de 14 ans. Elle poss\u00e8de des connaissances et une expertise dans les domaines de la sant\u00e9 et des services sociaux et a travaill\u00e9 avec des organisations s'occupant d'un large \u00e9ventail de questions communautaires.<\/p>\n<p>Plus r\u00e9cemment, Mme Wiggins a dirig\u00e9 la Community Caregiving Initiative, une initiative reconnue au niveau national et d\u00e9ploy\u00e9e \u00e0 l'\u00e9chelle du comt\u00e9 pour renforcer les soins prodigu\u00e9s \u00e0 une population vieillissante en aidant les aidants familiaux par le biais de services de sant\u00e9 int\u00e9gr\u00e9s et d'aides de proximit\u00e9.<\/p>\n<p>Outre son travail \u00e0 la fondation, Mme Wiggins s'est impliqu\u00e9e dans diverses organisations \u00e0 but non lucratif pendant plus de 30 ans, en tant que membre du conseil d'administration, membre du personnel et b\u00e9n\u00e9vole.<\/p>\n<p>La VCCF a \u00e9t\u00e9 cr\u00e9\u00e9e en 1987 pour d\u00e9velopper la philanthropie dans la r\u00e9gion par le biais de bourses, de subventions et de partenariats.<\/p>\n<p>Pour plus d'informations, visitez le site\u00a0<a class=\"autohyperlink\" href=\"https:\/\/vccf.org\/fr\/\">vccf.org<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":3088,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-3087","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-latest-coverage"],"_links":{"self":[{"href":"https:\/\/vccf.org\/fr\/wp-json\/wp\/v2\/posts\/3087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vccf.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vccf.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vccf.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/vccf.org\/fr\/wp-json\/wp\/v2\/comments?post=3087"}],"version-history":[{"count":0,"href":"https:\/\/vccf.org\/fr\/wp-json\/wp\/v2\/posts\/3087\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vccf.org\/fr\/wp-json\/wp\/v2\/media\/3088"}],"wp:attachment":[{"href":"https:\/\/vccf.org\/fr\/wp-json\/wp\/v2\/media?parent=3087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vccf.org\/fr\/wp-json\/wp\/v2\/categories?post=3087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vccf.org\/fr\/wp-json\/wp\/v2\/tags?post=3087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}