{"id":20931,"date":"2024-06-18T15:18:26","date_gmt":"2024-06-18T15:18:26","guid":{"rendered":"https:\/\/vccf.org\/?page_id=20931"},"modified":"2025-03-18T02:52:29","modified_gmt":"2025-03-18T09:52:29","slug":"donate","status":"publish","type":"page","link":"https:\/\/vccf.org\/it\/donate\/","title":{"rendered":"Donare"},"content":{"rendered":"<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vccf.org\/wp-content\/uploads\/2024\/09\/jJqJfy3-3.png\" alt=\"-jJqJfy3 3\" itemprop=\"image\" height=\"375\" width=\"519\" title=\"-JJqJfy3 3\" onerror=\"this.style.display='none'\"  \/>\n\t\t\t<a href=\"https:\/\/vccf.org\/it\/professional-advisor-faqs\/\" target=\"_self\">\n\t\t\t\t\t\t\tDomande frequenti sui consulenti professionali\n\t\t\t\t\t<\/a>\n\tModi per donare e<br \/>\nfare la differenza<br \/>\nnella Contea di Ventura\n\t<p>Ogni atto di donazione plasma il futuro della nostra comunit\u00e0. La vostra generosit\u00e0 alimenta il progresso, sostiene i bisognosi ed eleva la nostra casa comune.<\/p>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vccf.org\/wp-content\/uploads\/2024\/06\/donate-3.jpg\" alt=\"donate-3\" itemprop=\"image\" height=\"756\" width=\"1098\" title=\"donare-3\" onerror=\"this.style.display='none'\"  \/>\n\t\t\t<a href=\"\/it\/donor-faqs\/\" target=\"_self\">\n\t\t\t\t\t\t\tDomande frequenti sui donatori\n\t\t\t\t\t<\/a>\n\t<p>Supporto alla missione<\/p>\n\t<p>Un contributo generale al miglioramento della Contea di Ventura, CA.<\/p>\n\t\t\t<a href=\"\/it\/donate\/mission-support\/\" target=\"_self\">\n\t\t\t\t\t\t\tDonare\n\t\t\t\t\t<\/a>\n\t<p>Tributi duraturi<\/p>\n\t<p>Festeggiare una pietra miliare. Esprimere gratitudine. Salutare i risultati raggiunti. Commemorare la vita.<\/p>\n\t\t\t<a href=\"https:\/\/vccf.org\/it\/donate\/donate-to-a-tribute-fund\/\" target=\"_self\">\n\t\t\t\t\t\t\tDonare in onore di qualcuno\n\t\t\t\t\t<\/a>\n\t<p>Fondi specifici di sostegno<\/p>\n\t<p>Fate la differenza per le cause che vi stanno a cuore.<\/p>\n\t\t\t<a href=\"https:\/\/vccf.org\/it\/donate\/support-specific-funds-and-initiatives\/\" target=\"_self\">\n\t\t\t\t\t\t\tDonare a una causa specifica\n\t\t\t\t\t<\/a>","protected":false},"excerpt":{"rendered":"<p>Domande frequenti sui consulenti professionali Modi per donare e fare la differenza nella Contea di Ventura Ogni atto di donazione plasma il futuro della nostra comunit\u00e0. La vostra generosit\u00e0 alimenta il progresso, sostiene i bisognosi e...<\/p>","protected":false},"author":9,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"give_campaign_id":0,"footnotes":""},"class_list":["post-20931","page","type-page","status-publish","hentry"],"campaignId":"","_links":{"self":[{"href":"https:\/\/vccf.org\/it\/wp-json\/wp\/v2\/pages\/20931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vccf.org\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vccf.org\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vccf.org\/it\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/vccf.org\/it\/wp-json\/wp\/v2\/comments?post=20931"}],"version-history":[{"count":0,"href":"https:\/\/vccf.org\/it\/wp-json\/wp\/v2\/pages\/20931\/revisions"}],"wp:attachment":[{"href":"https:\/\/vccf.org\/it\/wp-json\/wp\/v2\/media?parent=20931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}